{"id":11326,"date":"2021-02-19T22:09:45","date_gmt":"2021-02-19T21:09:45","guid":{"rendered":"https:\/\/tiffanylampen.nl\/?post_type=product&#038;p=11326"},"modified":"2022-03-31T16:39:27","modified_gmt":"2022-03-31T14:39:27","slug":"5415-3","status":"publish","type":"product","link":"https:\/\/tiffanylampen.nl\/index.php\/en\/product\/5415-3\/","title":{"rendered":"5415"},"content":{"rendered":"<p>Ceiling lamp Libelle Nature \u00d8 40cm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ceiling lamp Libelle Nature \u00d8 40cm<\/p>\n","protected":false},"featured_media":669,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[848],"product_tag":[],"class_list":["post-11326","product","type-product","status-publish","has-post-thumbnail","product_cat-ceiling-lamps","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5415 - Tiffany Lampen<\/title>\n<meta name=\"description\" content=\"Ceiling lamp Libelle Nature \u00d8 40cm\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tiffanylampen.nl\/index.php\/en\/product\/5415-3\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5415 - Tiffany Lampen\" \/>\n<meta property=\"og:description\" content=\"Ceiling lamp Libelle Nature \u00d8 40cm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tiffanylampen.nl\/index.php\/en\/product\/5415-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Tiffany Lampen\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-31T14:39:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tiffanylampen.nl\/wp-content\/uploads\/2013\/06\/product_5_4_5415_.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"945\" \/>\n\t<meta property=\"og:image:height\" content=\"524\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tiffanylampen.nl\\\/index.php\\\/en\\\/product\\\/5415-3\\\/\",\"url\":\"https:\\\/\\\/tiffanylampen.nl\\\/index.php\\\/en\\\/product\\\/5415-3\\\/\",\"name\":\"5415 - Tiffany Lampen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tiffanylampen.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tiffanylampen.nl\\\/index.php\\\/en\\\/product\\\/5415-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tiffanylampen.nl\\\/index.php\\\/en\\\/product\\\/5415-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tiffanylampen.nl\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/product_5_4_5415_.gif\",\"datePublished\":\"2021-02-19T21:09:45+00:00\",\"dateModified\":\"2022-03-31T14:39:27+00:00\",\"description\":\"Ceiling lamp Libelle Nature \u00d8 40cm\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tiffanylampen.nl\\\/index.php\\\/en\\\/product\\\/5415-3\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tiffanylampen.nl\\\/index.php\\\/en\\\/product\\\/5415-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/tiffanylampen.nl\\\/index.php\\\/en\\\/product\\\/5415-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tiffanylampen.nl\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/product_5_4_5415_.gif\",\"contentUrl\":\"https:\\\/\\\/tiffanylampen.nl\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/product_5_4_5415_.gif\",\"width\":945,\"height\":524,\"caption\":\"5415 Dragonfly-0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tiffanylampen.nl\\\/index.php\\\/en\\\/product\\\/5415-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tiffanylampen.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/tiffanylampen.nl\\\/index.php\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"5415\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tiffanylampen.nl\\\/#website\",\"url\":\"https:\\\/\\\/tiffanylampen.nl\\\/\",\"name\":\"Tiffany Lampen\",\"description\":\"Tiffanylampe.nl de enige echte, gegarandeerd\",\"publisher\":{\"@id\":\"https:\\\/\\\/tiffanylampen.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tiffanylampen.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tiffanylampen.nl\\\/#organization\",\"name\":\"TiffanyLampen\",\"url\":\"https:\\\/\\\/tiffanylampen.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/tiffanylampen.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tiffanylampen.nl\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/tiffanylampen.nl\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/logo.png\",\"width\":562,\"height\":108,\"caption\":\"TiffanyLampen\"},\"image\":{\"@id\":\"https:\\\/\\\/tiffanylampen.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5415 - Tiffany Lampen","description":"Ceiling lamp Libelle Nature \u00d8 40cm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tiffanylampen.nl\/index.php\/en\/product\/5415-3\/","og_locale":"nl_NL","og_type":"article","og_title":"5415 - Tiffany Lampen","og_description":"Ceiling lamp Libelle Nature \u00d8 40cm","og_url":"https:\/\/tiffanylampen.nl\/index.php\/en\/product\/5415-3\/","og_site_name":"Tiffany Lampen","article_modified_time":"2022-03-31T14:39:27+00:00","og_image":[{"width":945,"height":524,"url":"https:\/\/tiffanylampen.nl\/wp-content\/uploads\/2013\/06\/product_5_4_5415_.gif","type":"image\/gif"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tiffanylampen.nl\/index.php\/en\/product\/5415-3\/","url":"https:\/\/tiffanylampen.nl\/index.php\/en\/product\/5415-3\/","name":"5415 - Tiffany Lampen","isPartOf":{"@id":"https:\/\/tiffanylampen.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tiffanylampen.nl\/index.php\/en\/product\/5415-3\/#primaryimage"},"image":{"@id":"https:\/\/tiffanylampen.nl\/index.php\/en\/product\/5415-3\/#primaryimage"},"thumbnailUrl":"https:\/\/tiffanylampen.nl\/wp-content\/uploads\/2013\/06\/product_5_4_5415_.gif","datePublished":"2021-02-19T21:09:45+00:00","dateModified":"2022-03-31T14:39:27+00:00","description":"Ceiling lamp Libelle Nature \u00d8 40cm","breadcrumb":{"@id":"https:\/\/tiffanylampen.nl\/index.php\/en\/product\/5415-3\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tiffanylampen.nl\/index.php\/en\/product\/5415-3\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/tiffanylampen.nl\/index.php\/en\/product\/5415-3\/#primaryimage","url":"https:\/\/tiffanylampen.nl\/wp-content\/uploads\/2013\/06\/product_5_4_5415_.gif","contentUrl":"https:\/\/tiffanylampen.nl\/wp-content\/uploads\/2013\/06\/product_5_4_5415_.gif","width":945,"height":524,"caption":"5415 Dragonfly-0"},{"@type":"BreadcrumbList","@id":"https:\/\/tiffanylampen.nl\/index.php\/en\/product\/5415-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tiffanylampen.nl\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/tiffanylampen.nl\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"5415"}]},{"@type":"WebSite","@id":"https:\/\/tiffanylampen.nl\/#website","url":"https:\/\/tiffanylampen.nl\/","name":"Tiffany Lampen","description":"Tiffanylampe.nl de enige echte, gegarandeerd","publisher":{"@id":"https:\/\/tiffanylampen.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tiffanylampen.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/tiffanylampen.nl\/#organization","name":"TiffanyLampen","url":"https:\/\/tiffanylampen.nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/tiffanylampen.nl\/#\/schema\/logo\/image\/","url":"https:\/\/tiffanylampen.nl\/wp-content\/uploads\/2020\/03\/logo.png","contentUrl":"https:\/\/tiffanylampen.nl\/wp-content\/uploads\/2020\/03\/logo.png","width":562,"height":108,"caption":"TiffanyLampen"},"image":{"@id":"https:\/\/tiffanylampen.nl\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tiffanylampen.nl\/index.php\/wp-json\/wp\/v2\/product\/11326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiffanylampen.nl\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tiffanylampen.nl\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/tiffanylampen.nl\/index.php\/wp-json\/wp\/v2\/comments?post=11326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tiffanylampen.nl\/index.php\/wp-json\/wp\/v2\/media\/669"}],"wp:attachment":[{"href":"https:\/\/tiffanylampen.nl\/index.php\/wp-json\/wp\/v2\/media?parent=11326"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/tiffanylampen.nl\/index.php\/wp-json\/wp\/v2\/product_brand?post=11326"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tiffanylampen.nl\/index.php\/wp-json\/wp\/v2\/product_cat?post=11326"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tiffanylampen.nl\/index.php\/wp-json\/wp\/v2\/product_tag?post=11326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}